{"id":14108,"date":"2018-03-27T16:56:59","date_gmt":"2018-03-27T09:56:59","guid":{"rendered":"https:\/\/www2.ananda.co.th\/blog\/thegenc\/?p=14108"},"modified":"2021-04-28T19:05:40","modified_gmt":"2021-04-28T12:05:40","slug":"%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%ab%e0%b8%99%e0%b8%94%e0%b8%b5-%e0%b8%a3%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.ananda.co.th\/blog\/thegenc\/%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%ab%e0%b8%99%e0%b8%94%e0%b8%b5-%e0%b8%a3%e0%b8%a7\/","title":{"rendered":"\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35?? \u0e23\u0e27\u0e21 5 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f"},"content":{"rendered":"<p class=\"p4\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/02-10.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-11809\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/02-10.jpg\" alt=\"02\" width=\"600\" height=\"314\"><\/a><\/p>\n<p class=\"p4\"><strong><span class=\"s1\">NOTE:<br \/>\n<\/span><\/strong><span class=\"s1\">&#8211; \u0e41\u0e15\u0e48\u0e40\u0e14\u0e34\u0e21<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19<\/b><\/span><span class=\"s4\"><b>\u201d (<\/b><\/span><span class=\"s1\"><b>\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35<\/b><\/span><span class=\"s4\"><b>)<\/b> <\/span><span class=\"s1\">\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19<\/span> <span class=\"s1\">\u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e40\u0e02\u0e15\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a<\/span> <span class=\"s1\">\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e15\u0e48\u0e2d\u0e21\u0e32<br \/>\n<\/span><span class=\"s4\"><b>&#8211; \u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f<\/span> <span class=\"s1\">\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35<\/span><span class=\"s4\"> 2511 <\/span><span class=\"s1\">\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e27\u0e46<\/span><span class=\"s4\"> 50 <\/span><span class=\"s1\">\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<br \/>\n<\/span><span class=\"s4\"><b>&#8211; \u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e17\u0e27\u0e35\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e2b\u0e23\u0e37\u0e2d<\/span> <span class=\"s1\">\u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07<\/span><span class=\"s4\"> 2 <\/span><span class=\"s1\">\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/span> <span class=\"s1\">\u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e01\u0e27\u0e48\u0e32<\/span><span class=\"s4\"> 60 <\/span><span class=\"s1\">\u0e44\u0e23\u0e48<\/span> <span class=\"s1\">\u0e0b\u0e36\u0e48\u0e07\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22<\/span><\/p>\n<p class=\"p6\"><span class=\"s1\">\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f\u0e44\u0e1b<\/span> <span class=\"s1\">\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e02\u0e2d\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e0a\u0e32\u0e27<\/span><span class=\"s4\"> GenCBlog <\/span><span class=\"s1\">\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p class=\"p8\" style=\"text-align: center;\"><span class=\"s1\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-01.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-11810\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-01.jpg\" alt=\"1803-GR-03-01\" width=\"600\" height=\"400\"><\/a>Cr: www.facebook.com\/pg\/<\/span><span class=\"s5\">\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e27\u0e31\u0e07\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19<\/span><\/p>\n<p class=\"p9\"><span class=\"s6\"><b>1.<\/b><\/span><span class=\"s1\"><b>\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d<\/b><\/span><span class=\"s6\"><b> (<\/b><\/span><span class=\"s1\"><b>\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35<\/b><\/span><span class=\"s6\"><b>)<\/b><\/span><\/p>\n<p class=\"p10\"><span class=\"s4\"><b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f\u0e43\u0e2b\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19<\/span> <span class=\"s1\">\u0e08\u0e27\u0e1a\u0e08\u0e19\u0e16\u0e36\u0e07\u0e23\u0e31\u0e0a\u0e2a\u0e21\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e38\u0e25\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27\u0e44\u0e14\u0e49\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e15\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e0a\u0e37\u0e48\u0e2d<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19<\/b><\/span><span class=\"s4\"><b>\u201d <\/b><\/span><span class=\"s1\">\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e21\u0e48<\/span><span class=\"s4\"> (<\/span><span class=\"s1\">\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35<\/span><span class=\"s4\">) <\/span><span class=\"s1\">\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d<\/span><\/p>\n<p class=\"p10\"><span class=\"s1\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19<\/span> <span class=\"s1\">\u0e2d\u0e32\u0e17\u0e34<\/span> <span class=\"s1\">\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e07\u0e04\u0e25\u0e2a\u0e21\u0e23\u0e2a<\/span> <span class=\"s1\">\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e07\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e46<\/span> <span class=\"s1\">\u0e41\u0e25\u0e30\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46<\/span> <span class=\"s1\">\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e16\u0e19\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/span> <span class=\"s1\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e01\u0e47\u0e2a\u0e38\u0e14\u0e41\u0e2a\u0e19\u0e08\u0e30\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22<\/span> <span class=\"s1\">\u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/span><\/p>\n<p class=\"p8\" style=\"text-align: center;\"><span class=\"s1\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-02.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-11811\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-02.jpg\" alt=\"1803-GR-03-02\" width=\"600\" height=\"400\"><\/a>Cr: travel.thaiza.com<\/span><\/p>\n<p class=\"p9\"><span class=\"s6\"><b>2.<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21<\/b><\/span><span class=\"s6\"><b> 8 (<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21<\/b><\/span><span class=\"s6\"><b> 8)<\/b><\/span><\/p>\n<p class=\"p5\"><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21<\/b><\/span><span class=\"s4\"><b> 8\u201d<\/b> <\/span><span class=\"s1\">\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e14\u0e39\u0e41\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23<\/span> <span class=\"s1\">\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e01\u0e27\u0e48\u0e32<\/span><span class=\"s4\"> 35 <\/span><span class=\"s1\">\u0e44\u0e23\u0e48<\/span> <span class=\"s1\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e15\u0e49\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21<\/span><span class=\"s4\"> 8 <\/span><span class=\"s1\">\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e15\u0e48\u0e32\u0e07\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e14\u0e35<\/span> <span class=\"s1\">\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21<\/span><span class=\"s4\"> 8 <\/span><span class=\"s1\">\u0e04\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32<\/span> <span class=\"s1\">\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07<\/span> <span class=\"s1\">\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19<\/span> <span class=\"s1\">\u0e40\u0e14\u0e34\u0e19<\/span> <span class=\"s1\">\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e46<\/span> <span class=\"s1\">\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e27\u0e17\u0e34\u0e27\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<\/span><\/p>\n<p class=\"p8\" style=\"text-align: center;\"><span class=\"s1\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-03.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11812\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-03.jpg\" alt=\"1803-GR-03-03\" width=\"600\" height=\"409\"><\/a>Cr: http:\/\/www.theprincessmothermemorialpark.org<\/span><\/p>\n<p class=\"p9\"><span class=\"s6\"><b>3.<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e22\u0e48\u0e32<\/b><\/span><span class=\"s6\"><b> (<\/b><\/span><span class=\"s1\"><b>\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e19<\/b><\/span><span class=\"s6\"><b>)<\/b><\/span><\/p>\n<p class=\"p10\"><span class=\"s4\"><b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e22\u0e48\u0e32<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e2b\u0e23\u0e37\u0e2d<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e15\u0e48\u0e32\u0e07\u0e19\u0e34\u0e22\u0e21\u0e21\u0e32\u0e27\u0e34\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22<\/span> <span class=\"s1\">\u0e42\u0e14\u0e22\u0e2a\u0e27\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32<\/span><span class=\"s4\"> 3 <\/span><span class=\"s1\">\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e19<\/span> <span class=\"s1\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e23\u0e13\u0e44\u0e21\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07<\/span> <span class=\"s1\">\u0e0a\u0e33\u0e21\u0e30\u0e19\u0e32\u0e14<\/span> <span class=\"s1\">\u0e1e\u0e38\u0e14\u0e08\u0e35\u0e1a<\/span> <span class=\"s1\">\u0e1b\u0e35\u0e1b<\/span> <span class=\"s1\">\u0e25\u0e35\u0e25\u0e32\u0e27\u0e14\u0e35<\/span> <span class=\"s1\">\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21\u0e2d\u0e48\u0e2d\u0e19\u0e46<\/span> <span class=\"s1\">\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e25\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e16\u0e19\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27<\/span> <span class=\"s1\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e22\u0e48\u0e32\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e23\u0e13\u0e35\u0e22\u0e01\u0e34\u0e08\u0e43\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e22\u0e48\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p class=\"p8\" style=\"text-align: center;\"><span class=\"s1\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-04.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11813\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-04.jpg\" alt=\"1803-GR-03-04\" width=\"600\" height=\"399\"><\/a>Cr: www.minpininteraction.com<\/span><\/p>\n<p class=\"p9\"><span class=\"s6\"><b>4.<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e17\u0e27\u0e35\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s6\"><b> (<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07<\/b><\/span><span class=\"s6\"><b> 2)<\/b><\/span><\/p>\n<p class=\"p5\"><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e17\u0e27\u0e35\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e14\u0e39\u0e41\u0e25\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32<\/span><span class=\"s4\"> 60 <\/span><span class=\"s1\">\u0e44\u0e23\u0e48\u0e1a\u0e19\u0e40\u0e02\u0e15\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32<\/span> <span class=\"s1\">\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e22\u0e48\u0e32\u0e19<\/span><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e15\u0e25\u0e32\u0e14\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35<\/b><\/span><span class=\"s4\"><b>\u201d (<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07<\/b><\/span><span class=\"s4\"><b> 2)<\/b> <\/span><span class=\"s1\">\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e22\u0e21\u0e32\u0e0a\u0e47\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<\/span><\/p>\n<p class=\"p5\"><span class=\"s1\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e17\u0e27\u0e35\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c\u0e16\u0e39\u0e01\u0e41\u0e1a\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19<\/span><span class=\"s4\"> 2 <\/span><span class=\"s1\">\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e46<\/span> <span class=\"s1\">\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48<\/span> <span class=\"s1\">\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30<\/span> <span class=\"s1\">\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e16\u0e19\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e34\u0e19<\/span><span class=\"s4\">&#8211;<\/span><span class=\"s1\">\u0e27\u0e34\u0e48\u0e07<\/span> <span class=\"s1\">\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19<\/span> <span class=\"s1\">\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32<\/span> <span class=\"s1\">\u0e25\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07<\/span> <span class=\"s1\">\u0e15\u0e25\u0e2d\u0e14\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e23\u0e13\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35<\/span><\/p>\n<p class=\"p8\" style=\"text-align: center;\"><span class=\"s1\"><a href=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-05.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11814\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2018\/03\/1803-GR-03-05.jpg\" alt=\"1803-GR-03-05\" width=\"600\" height=\"399\"><\/a>Cr: www.minpininteraction.com<\/span><\/p>\n<p class=\"p9\"><span class=\"s6\"><b>5.<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s6\"><b> (<\/b><\/span><span class=\"s1\"><b>\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32<\/b><\/span><span class=\"s6\"><b>)<\/b><\/span><\/p>\n<p class=\"p5\"><span class=\"s4\"> <b>\u201c<\/b><\/span><span class=\"s1\"><b>\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c<\/b><\/span><span class=\"s4\"><b>\u201d<\/b> <\/span><span class=\"s1\">\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f<\/span> <span class=\"s1\">\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32<\/span><span class=\"s4\"> 50 <\/span><span class=\"s1\">\u0e1b\u0e35<\/span> <span class=\"s1\">\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15\u0e17\u0e38\u0e48\u0e07\u0e04\u0e23\u0e38<\/span> <span class=\"s1\">\u0e27\u0e31\u0e14\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32<\/span> <span class=\"s1\">\u0e44\u0e21\u0e48\u0e43\u0e01\u0e25\u0e49\u0e44\u0e21\u0e48\u0e44\u0e01\u0e25\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e40\u0e17\u0e48\u0e32\u0e43\u0e14\u0e19\u0e31\u0e01<\/span><\/p>\n<p class=\"p5\"><span class=\"s1\">\u0e42\u0e14\u0e22\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/span> <span class=\"s1\">\u0e0b\u0e36\u0e48\u0e07\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e01\u0e48\u0e2d\u0e19<\/span><span class=\"s4\"> (<\/span><span class=\"s1\">\u0e2a\u0e27\u0e19\u0e2a\u0e49\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49<\/span><span class=\"s4\">) <\/span><span class=\"s1\">\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f<\/span> <span class=\"s1\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21\u0e44\u0e21\u0e49\u0e22\u0e37\u0e19\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<\/span> <span class=\"s1\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e21\u0e32\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e23\u0e34\u0e21\u0e19\u0e49\u0e33\u0e01\u0e47\u0e22\u0e48\u0e2d\u0e21\u0e44\u0e14\u0e49<\/span><\/p>\n<p class=\"p2\"><strong>\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08 \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c \u0e15\u0e23\u0e07\u0e08\u0e38\u0e14 \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e04\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e21\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e2d\u0e35\u0e01\u0e21\u0e34\u0e15\u0e34\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e35\u0e48 GEN-C Urban Living Solutions<br \/>\n<\/strong>Facebook: <a href=\"https:\/\/www.facebook.com\/ananda.pcl\" target=\"_blank\" rel=\"noopener\">Ananda Development<\/a><br \/>\nInstagram: <a href=\"https:\/\/www.instagram.com\/ananda_development\" target=\"_blank\" rel=\"noopener\">ananda_development<\/a><br \/>\nYoutube: <a href=\"https:\/\/www.youtube.com\/user\/IdeoCondo\" target=\"_blank\" rel=\"noopener\">Ananda Development<\/a><\/p>\n<p class=\"p2\"><em><span class=\"s1\">\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e08\u0e32\u0e01<\/span><span class=\"s2\">: th.wikipedia.org<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTE: &#8211; \u0e41\u0e15\u0e48\u0e40\u0e14\u0e34\u0e21 \u201c\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u201d \u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07 \u201c\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u201d (\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35) \u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e40\u0e02\u0e15\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e22\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e15\u0e48\u0e2d\u0e21\u0e32 &#8211; \u201c\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c\u201d \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e1b\u0e35 2511 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e27\u0e46 50 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 &#8211; \u201c\u0e2a\u0e27\u0e19\u0e17\u0e27\u0e35\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c\u201d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07 2 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e17\u0e35\u0e48\u0e21\u0e35\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e01\u0e27\u0e48\u0e32 60 \u0e44\u0e23\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f\u0e44\u0e1b \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e02\u0e2d\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e0a\u0e32\u0e27 GenCBlog \u0e17\u0e35\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e41\u0e16\u0e1a\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e1a Cr: www.facebook.com\/pg\/\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e27\u0e31\u0e07\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19 1.\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d (\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35) \u201c\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u201d \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15 \u201c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u201d \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f\u0e43\u0e2b\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e08\u0e27\u0e1a\u0e08\u0e19\u0e16\u0e36\u0e07\u0e23\u0e31\u0e0a\u0e2a\u0e21\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e38\u0e25\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27\u0e44\u0e14\u0e49\u0e17\u0e23\u0e07\u0e1e\u0e23\u0e30\u0e01\u0e23\u0e38\u0e13\u0e32\u0e42\u0e1b\u0e23\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e15\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e0a\u0e37\u0e48\u0e2d \u201c\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u201d \u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e15\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e21\u0e48 (\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35) \u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e17\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e40\u0e23\u0e37\u0e2d \u0e20\u0e32\u0e22\u0e43\u0e19\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e17\u0e34 \u0e1e\u0e34\u0e18\u0e35\u0e21\u0e07\u0e04\u0e25\u0e2a\u0e21\u0e23\u0e2a \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e07\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e16\u0e19\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e19\u0e31\u0e19\u0e17\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e17\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e01\u0e47\u0e2a\u0e38\u0e14\u0e41\u0e2a\u0e19\u0e08\u0e30\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 Cr: travel.thaiza.com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12,5],"tags":[132,131,69,70],"class_list":["post-14108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finding-oasis","category-roam-around","tag-thonburi","tag-131","tag-69","tag-70"],"_links":{"self":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/14108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/comments?post=14108"}],"version-history":[{"count":0,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/14108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media\/28585"}],"wp:attachment":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media?parent=14108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/categories?post=14108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/tags?post=14108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}