{"id":27456,"date":"2021-04-06T12:07:05","date_gmt":"2021-04-06T05:07:05","guid":{"rendered":"https:\/\/www.ananda.co.th\/blog\/thegenc\/?p=27456"},"modified":"2021-04-09T17:26:23","modified_gmt":"2021-04-09T10:26:23","slug":"weekend-chill-space","status":"publish","type":"post","link":"https:\/\/www.ananda.co.th\/blog\/thegenc\/weekend-chill-space\/","title":{"rendered":"\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35! \u0e0a\u0e34\u0e04\u0e17\u0e38\u0e01\u0e40\u0e27\u0e25\u0e32 \u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e47\u0e0a\u0e34\u0e25\u0e44\u0e14\u0e49"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19\u0e23\u0e30\u0e2d\u0e38 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e44\u0e2b\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e34\u0e48\u0e07\u0e46 \u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e21\u0e38\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e21\u0e38\u0e21\u0e0a\u0e34\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e34\u0e25\u0e43\u0e19\u0e27\u0e31\u0e19\u0e27\u0e48\u0e32\u0e07 \u0e25\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e39 4 \u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e21\u0e38\u0e21\u0e0a\u0e34\u0e04\u0e46 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35! \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e2a\u0e38\u0e14\u0e46<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-27460\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01.jpg\" alt=\"\" width=\"1145\" height=\"764\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01.jpg 1145w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01-824x550.jpg 824w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01-300x200.jpg 300w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01-599x400.jpg 599w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01-770x514.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/01-272x182.jpg 272w\" sizes=\"(max-width: 1145px) 100vw, 1145px\" \/><\/p>\n<ol>\n<li><strong> \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e38\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07<\/strong><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e21\u0e38\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u201d \u0e41\u0e2a\u0e19\u0e0a\u0e34\u0e04\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e25 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e44\u0e21\u0e49\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e21\u0e32\u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e42\u0e15\u0e4a\u0e30\u0e01\u0e25\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e42\u0e15\u0e4a\u0e30 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e2a\u0e27\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e19\u0e39\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e15\u0e48\u0e16\u0e39\u0e01\u0e43\u0e08 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e01\u0e49\u0e27\u0e42\u0e1b\u0e23\u0e14\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e0b\u0e2d\u0e07\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e23\u0e48\u0e2d\u0e22<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e41\u0e04\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e41\u0e25\u0e30\u0e42\u0e15\u0e4a\u0e30\u0e2a\u0e31\u0e01\u0e15\u0e31\u0e27\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e43\u0e2a\u0e44\u0e14\u0e49 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e22\u0e32\u0e21\u0e40\u0e0a\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e23\u0e33\u0e44\u0e23 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-27459\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02.jpg\" alt=\"\" width=\"1145\" height=\"763\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02.jpg 1145w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02-825x550.jpg 825w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02-300x200.jpg 300w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02-600x400.jpg 600w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02-770x513.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/02-272x182.jpg 272w\" sizes=\"(max-width: 1145px) 100vw, 1145px\" \/><\/p>\n<ol start=\"2\">\n<li><strong> \u0e08\u0e21\u0e14\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a<\/strong><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e21\u0e38\u0e21 \u2018\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u2019 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e38\u0e13\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2d\u0e14\u0e34\u0e40\u0e23\u0e01\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e33\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e04\u0e19\u0e42\u0e1b\u0e23\u0e14, \u0e01\u0e32\u0e23\u0e08\u0e21\u0e14\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e43\u0e19\u0e42\u0e25\u0e01\u0e0b\u0e35\u0e23\u0e35\u0e48\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e1a\u0e15\u0e32\u0e1f\u0e31\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e19\u0e38\u0e48\u0e21\u0e46 \u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e04\u0e19\u0e42\u0e1b\u0e23\u0e14 \u0e2f\u0e25\u0e2f \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e44\u0e2b\u0e19 \u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e01\u0e47\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e30\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e07\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e0a\u0e34\u0e49\u0e19 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d \u201c\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u201d \u0e1e\u0e23\u0e30\u0e40\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e01\u0e4b\u0e0a\u0e34\u0e04\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e44\u0e14\u0e49 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e43\u0e1a\u0e2a\u0e27\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e25\u0e39\u0e01\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-27458\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03.jpg\" alt=\"\" width=\"1145\" height=\"763\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03.jpg 1145w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03-825x550.jpg 825w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03-300x200.jpg 300w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03-600x400.jpg 600w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03-770x513.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/03-272x182.jpg 272w\" sizes=\"(max-width: 1145px) 100vw, 1145px\" \/><\/p>\n<ol start=\"3\">\n<li><strong> \u0e21\u0e38\u0e21\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48 \u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/strong><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e21\u0e35\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e35\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e2d\u0e27\u0e14\u0e0a\u0e32\u0e27\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e40\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u201d \u0e2b\u0e25\u0e32\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e04\u0e38\u0e13\u0e0a\u0e2d\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e41\u0e1e\u0e25\u0e19\u0e08\u0e30\u0e08\u0e31\u0e14\u0e21\u0e38\u0e21\u0e2a\u0e27\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e41\u0e14\u0e14\u0e19\u0e49\u0e2d\u0e22\u0e19\u0e49\u0e33\u0e19\u0e49\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e25\u0e39\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e43\u0e1a\u0e2a\u0e27\u0e22\u0e01\u0e47\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e43\u0e2b\u0e49\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e0a\u0e34\u0e04\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-27457\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04.jpg\" alt=\"\" width=\"1145\" height=\"763\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04.jpg 1145w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04-825x550.jpg 825w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04-300x200.jpg 300w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04-600x400.jpg 600w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04-770x513.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/04\/04-272x182.jpg 272w\" sizes=\"(max-width: 1145px) 100vw, 1145px\" \/><\/p>\n<ol start=\"4\">\n<li><strong> \u0e2a\u0e38\u0e02\u0e43\u0e08\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21<\/strong><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e21\u0e38\u0e21\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e04\u0e19\u0e23\u0e31\u0e01\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48\u0e44\u0e0b\u0e2a\u0e4c\u0e08\u0e34\u0e4b\u0e27 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e31\u0e48\u0e19\u0e21\u0e32\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e32\u0e2a\u0e25\u0e31\u0e1a\u0e2a\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e23\u0e2d\u0e1a\u0e46 \u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e2d\u0e32\u0e17\u0e34 \u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14\u0e25\u0e32\u0e22\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e1a\u0e44\u0e21\u0e49 \u0e17\u0e35\u0e48\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e43\u0e2b\u0e49\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e43\u0e08\u0e14\u0e49\u0e27\u0e22\u0e42\u0e15\u0e4a\u0e30\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e15\u0e31\u0e27\u0e2a\u0e27\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e08\u0e32\u0e01 4 \u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e0a\u0e34\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35 \u201c\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u201d \u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07 4 \u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e15\u0e48\u0e32\u0e07\u0e21\u0e35\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e07\u0e40\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e34\u0e04\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e19\u0e35\u0e49 \u0e25\u0e2d\u0e07\u0e21\u0e32\u0e02\u0e22\u0e31\u0e1a\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e14 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19\u0e23\u0e30\u0e2d\u0e38 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e44\u0e2b\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e34\u0e48\u0e07\u0e46 \u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e21\u0e38\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e21\u0e38\u0e21\u0e0a\u0e34\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e34\u0e25\u0e43\u0e19\u0e27\u0e31\u0e19\u0e27\u0e48\u0e32\u0e07 \u0e25\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e39 4 \u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e21\u0e38\u0e21\u0e0a\u0e34\u0e04\u0e46 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35! \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e2a\u0e38\u0e14\u0e46 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e38\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07 \u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e21\u0e38\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u201d \u0e41\u0e2a\u0e19\u0e0a\u0e34\u0e04\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e25 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e44\u0e21\u0e49\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e21\u0e32\u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e42\u0e15\u0e4a\u0e30\u0e01\u0e25\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e42\u0e15\u0e4a\u0e30 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e2a\u0e27\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e19\u0e39\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e15\u0e48\u0e16\u0e39\u0e01\u0e43\u0e08 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e01\u0e49\u0e27\u0e42\u0e1b\u0e23\u0e14\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e0b\u0e2d\u0e07\u0e15\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e41\u0e04\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e41\u0e25\u0e30\u0e42\u0e15\u0e4a\u0e30\u0e2a\u0e31\u0e01\u0e15\u0e31\u0e27\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e43\u0e2a\u0e44\u0e14\u0e49 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e22\u0e32\u0e21\u0e40\u0e0a\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e23\u0e33\u0e44\u0e23 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e08\u0e21\u0e14\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a \u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e02\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e21\u0e38\u0e21 \u2018\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u2019 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e38\u0e13\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2d\u0e14\u0e34\u0e40\u0e23\u0e01\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e37\u0e48\u0e21\u0e14\u0e48\u0e33\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e04\u0e19\u0e42\u0e1b\u0e23\u0e14, \u0e01\u0e32\u0e23\u0e08\u0e21\u0e14\u0e34\u0e48\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e43\u0e19\u0e42\u0e25\u0e01\u0e0b\u0e35\u0e23\u0e35\u0e48\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e1a\u0e15\u0e32\u0e1f\u0e31\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e19\u0e38\u0e48\u0e21\u0e46 \u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e04\u0e19\u0e42\u0e1b\u0e23\u0e14 \u0e2f\u0e25\u0e2f \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e44\u0e2b\u0e19 \u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e01\u0e47\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e30\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e07\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e0a\u0e34\u0e49\u0e19 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d \u201c\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u201d \u0e1e\u0e23\u0e30\u0e40\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e01\u0e4b\u0e0a\u0e34\u0e04\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e44\u0e14\u0e49 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e43\u0e1a\u0e2a\u0e27\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e25\u0e39\u0e01\u0e44\u0e14\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e38\u0e21\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48 \u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e21\u0e35\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e35\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e19\u0e23\u0e21\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e38\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e2d\u0e27\u0e14\u0e0a\u0e32\u0e27\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e21\u0e38\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e40\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 \u201c\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u201d \u0e2b\u0e25\u0e32\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e04\u0e38\u0e13\u0e0a\u0e2d\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e41\u0e1e\u0e25\u0e19\u0e08\u0e30\u0e08\u0e31\u0e14\u0e21\u0e38\u0e21\u0e2a\u0e27\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e19\u0e42\u0e14 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":27461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6,15],"tags":[641,563,141],"class_list":["post-27456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifehacks","category-live-with-passion","tag-641","tag-563","tag-141"],"_links":{"self":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/27456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/comments?post=27456"}],"version-history":[{"count":0,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/27456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media\/27461"}],"wp:attachment":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media?parent=27456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/categories?post=27456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/tags?post=27456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}