{"id":33292,"date":"2021-12-20T11:33:24","date_gmt":"2021-12-20T04:33:24","guid":{"rendered":"https:\/\/www.ananda.co.th\/blog\/thegenc\/?p=33292"},"modified":"2021-12-20T11:33:24","modified_gmt":"2021-12-20T04:33:24","slug":"konmari","status":"publish","type":"post","link":"https:\/\/www.ananda.co.th\/blog\/thegenc\/konmari\/","title":{"rendered":"\u0e17\u0e34\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e21\u0e48! \u0e0a\u0e27\u0e19\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e35 2022 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 KONMARI"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e0a\u0e27\u0e19\u0e17\u0e34\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22! \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e25\u0e19\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e34\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1b\u0e35 2022 \u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e23\u0e07\u0e44\u0e2b\u0e19 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19 \u2018\u0e04\u0e19\u0e21\u0e32\u0e23\u0e34\u2019 (KonMari) \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e34\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e09\u0e1a\u0e31\u0e1a \u201c\u0e04\u0e19\u0e42\u0e14 \u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u201d\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2026\u0e16\u0e49\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e38\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e1b\u0e0a\u0e21\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-33293\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02.jpg\" alt=\"\" width=\"1201\" height=\"1200\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02.jpg 1201w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-400x400.jpg 400w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-550x550.jpg 550w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-200x200.jpg 200w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-60x60.jpg 60w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-770x769.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-110x110.jpg 110w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-02-600x600.jpg 600w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p><strong>\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e21\u0e27\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e14\u0e19\u0e48\u0e32\u0e1b\u0e27\u0e14\u0e2b\u0e31\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e0a\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2b\u0e22\u0e34\u0e1a\u0e21\u0e32\u0e43\u0e2a\u0e48\u0e40\u0e25\u0e22 \u0e08\u0e30\u0e17\u0e34\u0e49\u0e07\u0e08\u0e36\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e01\u0e47\u0e23\u0e01\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e1b\u0e25\u0e48\u0e32<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e08\u0e36\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49 \u201c\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u201d \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e27\u0e48\u0e32\u0e21\u0e35\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e2d\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e15\u0e31\u0e14\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e46\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e04\u0e37\u0e2d\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u2018\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u2019 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2b\u0e22\u0e34\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e2b\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e47\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e2b\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e34\u0e18\u0e35\u0e1e\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e2b\u0e32\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2b\u0e22\u0e34\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-33294\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03.jpg\" alt=\"\" width=\"1201\" height=\"1200\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03.jpg 1201w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-400x400.jpg 400w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-550x550.jpg 550w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-200x200.jpg 200w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-60x60.jpg 60w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-770x769.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-110x110.jpg 110w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-03-600x600.jpg 600w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p><strong>\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 \u2018\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u2019 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e34\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e21\u0e32\u0e17\u0e35\u0e25\u0e30\u0e40\u0e25\u0e48\u0e21 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 \u201c\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e19\u0e33\u0e15\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e14\u0e49\u0e27\u0e22\u201d \u0e01\u0e47\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e19\u0e31\u0e49\u0e19\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e25\u0e30\u0e40\u0e25\u0e48\u0e21\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e44\u0e27\u0e49\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e47\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e25\u0e48\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e1e\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-33295\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04.jpg\" alt=\"\" width=\"1201\" height=\"1200\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04.jpg 1201w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-400x400.jpg 400w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-550x550.jpg 550w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-200x200.jpg 200w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-60x60.jpg 60w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-770x769.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-110x110.jpg 110w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-04-600x600.jpg 600w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p><strong>\u0e2b\u0e21\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e31\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e08\u0e38\u0e01\u0e08\u0e34\u0e01\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e19\u0e49\u0e2d\u0e22\u0e46 \u0e41\u0e15\u0e48\u0e01\u0e34\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e33\u0e1a\u0e32\u0e01\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e22\u0e31\u0e07\u0e04\u0e07\u0e22\u0e36\u0e14\u0e2b\u0e25\u0e31\u0e01 \u201c\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u201d \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e15\u0e48\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33 \u2018\u0e01\u0e25\u0e48\u0e2d\u0e07\u2019 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e0b\u0e49\u0e33 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e08\u0e19\u0e25\u0e37\u0e21 \u0e1e\u0e2d\u0e21\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e47\u0e19 \u0e2b\u0e32\u0e44\u0e21\u0e48\u0e40\u0e08\u0e2d \u0e01\u0e47\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e0b\u0e49\u0e33 \u0e42\u0e14\u0e22\u0e02\u0e2d\u0e07\u0e43\u0e19 1 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33296\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05.jpg\" alt=\"\" width=\"1201\" height=\"1200\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05.jpg 1201w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-400x400.jpg 400w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-550x550.jpg 550w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-200x200.jpg 200w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-60x60.jpg 60w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-770x769.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-110x110.jpg 110w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-05-600x600.jpg 600w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p><strong>\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u0e0a\u0e48\u0e27\u0e07 Work from home \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e08\u0e36\u0e07\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e44\u0e27\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 3 \u0e01\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e04\u0e37\u0e2d<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e34\u0e25\u0e04\u0e48\u0e32\u0e44\u0e1f \u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e2f\u0e25\u0e2f \u0e2b\u0e32\u0e01\u0e40\u0e23\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2a\u0e48\u0e41\u0e1f\u0e49\u0e21 \u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e49\u0e25\u0e34\u0e49\u0e19\u0e0a\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2b\u0e22\u0e34\u0e1a\u0e21\u0e32\u0e14\u0e39\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e2f\u0e25\u0e2f \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e27\u0e32\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e21\u0e38\u0e21\u0e43\u0e14\u0e21\u0e38\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e43\u0e2a\u0e48\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e1a\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e01\u0e47\u0e04\u0e27\u0e23\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e04\u0e37\u0e19\u0e44\u0e1b\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-33298\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07.jpg\" alt=\"\" width=\"1201\" height=\"1200\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07.jpg 1201w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-400x400.jpg 400w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-550x550.jpg 550w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-200x200.jpg 200w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-60x60.jpg 60w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-770x769.jpg 770w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-110x110.jpg 110w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2021\/12\/Ananda_Dec2021_Content_KONMARI_01-07-600x600.jpg 600w\" sizes=\"(max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p><strong>\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">\u0e0a\u0e48\u0e27\u0e07 Work from home \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e08\u0e36\u0e07\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e44\u0e27\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19 \u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 3 \u0e01\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e04\u0e37\u0e2d<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e34\u0e25\u0e04\u0e48\u0e32\u0e44\u0e1f \u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e2f\u0e25\u0e2f \u0e2b\u0e32\u0e01\u0e40\u0e23\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e2f\u0e25\u0e2f \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e08\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e08\u0e36\u0e07\u0e04\u0e27\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2a\u0e48\u0e41\u0e1f\u0e49\u0e21 \u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e49\u0e25\u0e34\u0e49\u0e19\u0e0a\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2b\u0e22\u0e34\u0e1a\u0e21\u0e32\u0e14\u0e39\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e2d\u0e01\u0e21\u0e32 \u0e2f\u0e25\u0e2f \u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e27\u0e32\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e21\u0e38\u0e21\u0e43\u0e14\u0e21\u0e38\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e43\u0e2a\u0e48\u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e27\u0e32\u0e07\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e1a\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e01\u0e47\u0e04\u0e27\u0e23\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e04\u0e37\u0e19\u0e44\u0e1b\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e21\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e43\u0e08<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e43\u0e08 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e08\u0e36\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e02\u0e2d\u0e07\u0e2b\u0e21\u0e27\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e19\u0e31\u0e48\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2b\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e41\u0e23\u0e01 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e34\u0e14\u0e02\u0e31\u0e14 \u0e22\u0e31\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e25\u0e31\u0e07\u0e40\u0e25 \u0e41\u0e15\u0e48\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2b\u0e21\u0e27\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e32\u0e21\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e34\u0e49\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e23\u0e34\u0e04 \u2018\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u2019 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e34\u0e49\u0e07\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e34\u0e21\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e27\u0e19\u0e17\u0e34\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22! \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e25\u0e19\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e34\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1b\u0e35 2022 \u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e23\u0e07\u0e44\u0e2b\u0e19 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19 \u2018\u0e04\u0e19\u0e21\u0e32\u0e23\u0e34\u2019 (KonMari) \u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e34\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e09\u0e1a\u0e31\u0e1a \u201c\u0e04\u0e19\u0e42\u0e14 \u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u201d\u00a0\u00a0 \u2026\u0e16\u0e49\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e38\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e1b\u0e0a\u0e21\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e2b\u0e21\u0e27\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e14\u0e19\u0e48\u0e32\u0e1b\u0e27\u0e14\u0e2b\u0e31\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1a\u0e32\u0e07\u0e0a\u0e38\u0e14 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e22\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2b\u0e22\u0e34\u0e1a\u0e21\u0e32\u0e43\u0e2a\u0e48\u0e40\u0e25\u0e22 \u0e08\u0e30\u0e17\u0e34\u0e49\u0e07\u0e08\u0e36\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e01\u0e47\u0e23\u0e01\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e08\u0e36\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49 \u201c\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u201d \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e27\u0e48\u0e32\u0e21\u0e35\u0e40\u0e22\u0e2d\u0e30\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e2d\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e15\u0e31\u0e14\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e46\u00a0 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e21\u0e32\u0e23\u0e34\u0e40\u0e2d\u0e30\u0e04\u0e37\u0e2d\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u2018\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u2019 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2b\u0e22\u0e34\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e2b\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e47\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e2b\u0e19\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b\u00a0 \u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e34\u0e18\u0e35\u0e1e\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e2b\u0e32\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2b\u0e22\u0e34\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e04\u0e23\u0e31\u0e1a \u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u00a0 \u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 \u2018\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u2019 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e34\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e21\u0e32\u0e17\u0e35\u0e25\u0e30\u0e40\u0e25\u0e48\u0e21 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e16\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 \u201c\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e19\u0e33\u0e15\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e14\u0e49\u0e27\u0e22\u201d \u0e01\u0e47\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e19\u0e31\u0e49\u0e19\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49 \u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e25\u0e30\u0e40\u0e25\u0e48\u0e21\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e44\u0e27\u0e49\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e47\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e40\u0e25\u0e48\u0e21\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u00a0 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e25\u0e48\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e1e\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e14\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e21\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30\u00a0 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e27\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e31\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e08\u0e38\u0e01\u0e08\u0e34\u0e01\u0e40\u0e25\u0e47\u0e01\u0e46 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33297,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6,15],"tags":[812,811],"class_list":["post-33292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifehacks","category-live-with-passion","tag-konmari","tag-811"],"_links":{"self":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/33292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/comments?post=33292"}],"version-history":[{"count":0,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/33292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media\/33297"}],"wp:attachment":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media?parent=33292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/categories?post=33292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/tags?post=33292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}