{"id":34887,"date":"2022-05-19T00:00:19","date_gmt":"2022-05-18T17:00:19","guid":{"rendered":"https:\/\/www.ananda.co.th\/blog\/thegenc\/?p=34887"},"modified":"2022-05-17T15:12:58","modified_gmt":"2022-05-17T08:12:58","slug":"%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b8%a1%e0%b8%b9%e0%b8%ab%e0%b9%89%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%a5%e0%b8%b2%e0%b8%94-5-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%ab%e0%b8%a7%e0%b9%89%e0%b8%97%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b9%80%e0%b8%a7%e0%b8%aa%e0%b8%aa%e0%b8%b8%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%93","status":"publish","type":"post","link":"https:\/\/www.ananda.co.th\/blog\/thegenc\/%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b8%a1%e0%b8%b9%e0%b8%ab%e0%b9%89%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%a5%e0%b8%b2%e0%b8%94-5-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%84%e0%b8%ab%e0%b8%a7%e0%b9%89%e0%b8%97%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b9%80%e0%b8%a7%e0%b8%aa%e0%b8%aa%e0%b8%b8%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%93\/","title":{"rendered":"\u0e2a\u0e32\u0e22\u0e21\u0e39\u0e2b\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e14 5 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e27\u0e49\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e02\u0e2d\u0e1e\u0e23\u0e2a\u0e30\u0e40\u0e14\u0e32\u0e30\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c"},"content":{"rendered":"<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e22\u0e21\u0e39\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e23\u0e30\u0e41\u0e2a\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e35 2565 \u0e19\u0e35\u0e49\u0e04\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e49\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e44\u0e2b\u0e27\u0e49\u0e02\u0e2d\u0e1e\u0e23 \u201c\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e49\u0e32\u0e27\u0e08\u0e15\u0e38\u0e42\u0e25\u0e01\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e34\u0e28\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e01\u0e1b\u0e31\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e34\u0e28\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e08\u0e15\u0e38\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e34\u0e01\u0e32 \u0e40\u0e17\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e16\u0e37\u0e2d\u0e15\u0e30\u0e1a\u0e2d\u0e07 \u0e21\u0e35\u0e17\u0e48\u0e32\u0e17\u0e32\u0e07\u0e19\u0e48\u0e32\u0e40\u0e01\u0e23\u0e07\u0e02\u0e32\u0e21 \u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e0a\u0e31\u0e48\u0e27\u0e23\u0e49\u0e32\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e21\u0e32\u0e01 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e02\u0e2d\u0e1e\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e25\u0e30\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e1b\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e17\u0e48\u0e32\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35 5 \u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e19\u0e34\u0e22\u0e21\u0e44\u0e1b\u0e44\u0e2b\u0e27\u0e49\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e31\u0e19<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-34889\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-844x550.jpg\" alt=\"\" width=\"844\" height=\"550\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-844x550.jpg 844w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-614x400.jpg 614w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-307x200.jpg 307w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-1536x1001.jpg 1536w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-2048x1334.jpg 2048w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-01-10-770x502.jpg 770w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<p><strong>\u0e27\u0e31\u0e14\u0e08\u0e38\u0e2c\u0e32\u0e21\u0e13\u0e35 \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21<\/strong><\/p>\n<p>\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e08\u0e38\u0e14\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e27\u0e31\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e14\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e41\u0e16\u0e27\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e17\u0e2d\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e23\u0e38\u0e14\u0e42\u0e17\u0e23\u0e21\u0e15\u0e32\u0e21\u0e01\u0e32\u0e25\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e30\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35 2459 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e23\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2d\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e44\u0e14\u0e49\u0e21\u0e32\u0e02\u0e2d\u0e1e\u0e23\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e17\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e32\u0e22 <br \/>\n\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: 93 \u0e2b\u0e21\u0e39\u0e48 9 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21<br \/>\n\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: <a href=\"https:\/\/goo.gl\/maps\/rxGYvStCHWwC4uXj8\" target=\"_blank\" rel=\"noopener\">https:\/\/goo.gl\/maps\/rxGYvStCHWwC4uXj8<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-34890\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-844x550.jpg\" alt=\"\" width=\"844\" height=\"550\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-844x550.jpg 844w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-614x400.jpg 614w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-307x200.jpg 307w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-1536x1001.jpg 1536w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-2048x1335.jpg 2048w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-02-1-10-770x502.jpg 770w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<p><strong>\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e17\u0e31\u0e28\u0e19\u0e40\u0e17\u0e1e\u0e27\u0e23\u0e32\u0e23\u0e32\u0e21\u0e23\u0e32\u0e0a\u0e27\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/strong><\/p>\n<p>\u0e27\u0e31\u0e14\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e27\u0e31\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e23\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e2d\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e0a\u0e34\u0e07\u0e0a\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e27\u0e31\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e28\u0e23\u0e35\u0e28\u0e32\u0e01\u0e22\u0e21\u0e38\u0e13\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e48\u0e2d\u0e42\u0e15\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e39\u0e1b\u0e2b\u0e25\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e33\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 600 \u0e1b\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e14\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16 2 \u0e2b\u0e25\u0e31\u0e07\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e49\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16\u0e17\u0e35\u0e48\u0e22\u0e32\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e35\u0e08\u0e34\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1d\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e17\u0e35\u0e48\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e07\u0e14\u0e07\u0e32\u0e21\u0e21\u0e32\u0e01\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e30\u0e21\u0e35\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e21\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 <br \/>\n\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: 146 \u0e16\u0e19\u0e19\u0e15\u0e35\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 (\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e2a\u0e32\u0e0a\u0e34\u0e07\u0e0a\u0e49\u0e32)<br \/>\n\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: <a href=\"https:\/\/goo.gl\/maps\/pSDYiqnFwpyejfaD7\" target=\"_blank\" rel=\"noopener\">https:\/\/goo.gl\/maps\/pSDYiqnFwpyejfaD7<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-34891\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-844x550.jpg\" alt=\"\" width=\"844\" height=\"550\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-844x550.jpg 844w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-614x400.jpg 614w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-307x200.jpg 307w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-1536x1001.jpg 1536w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-2048x1335.jpg 2048w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-03-1-10-770x502.jpg 770w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<p><strong>\u0e27\u0e31\u0e14\u0e21\u0e07\u0e04\u0e25\u0e08\u0e34\u0e19\u0e14\u0e32\u0e23\u0e32\u0e21 \u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21<\/strong><\/p>\n<p>\u0e27\u0e31\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e35\u0e22\u0e01\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e27\u0e31\u0e19\u0e44\u0e23\u0e48\u0e02\u0e34\u0e07 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e48\u0e2d\u0e27\u0e31\u0e14\u0e44\u0e23\u0e48\u0e02\u0e34\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e39\u0e1b\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e1b\u0e32\u0e07\u0e21\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e21\u0e35\u0e1e\u0e38\u0e17\u0e18\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e14\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e38\u0e17\u0e18\u0e28\u0e34\u0e25\u0e1b\u0e4c 3 \u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2d\u0e07\u0e04\u0e4c\u0e2a\u0e35\u0e17\u0e2d\u0e07\u0e22\u0e37\u0e19\u0e40\u0e14\u0e48\u0e19\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e44\u0e14\u0e49\u0e21\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e02\u0e2d\u0e1e\u0e23\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e27\u0e31\u0e14\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2d\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e19\u0e32\u0e14 5.5 \u0e40\u0e21\u0e15\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e38\u0e14\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 <br \/>\n\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: 51 \u0e2b\u0e21\u0e39\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e15\u0e33\u0e1a\u0e25\u0e44\u0e23\u0e48\u0e02\u0e34\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2a\u0e32\u0e21\u0e1e\u0e23\u0e32\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21<br \/>\n\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: <a href=\"https:\/\/goo.gl\/maps\/DBUynGg5KhXCPimD9\" target=\"_blank\" rel=\"noopener\">https:\/\/goo.gl\/maps\/DBUynGg5KhXCPimD9<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-34892\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-844x550.jpg\" alt=\"\" width=\"844\" height=\"550\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-844x550.jpg 844w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-614x400.jpg 614w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-307x200.jpg 307w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-1536x1001.jpg 1536w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-2048x1335.jpg 2048w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-04-1-10-770x502.jpg 770w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<p><strong>\u0e27\u0e31\u0e14\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/strong><\/p>\n<p>\u0e2d\u0e35\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e04\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e1a\u0e32\u0e07\u0e0a\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e21\u0e39\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e14\u0e36\u0e01\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e02\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e21. \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e19\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e21\u0e32\u0e27\u0e19\u0e14\u0e49\u0e32\u0e19\u0e02\u0e27\u0e32\u0e23\u0e2d\u0e1a\u0e15\u0e30\u0e1a\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 9 \u0e23\u0e2d\u0e1a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e18\u0e34\u0e29\u0e10\u0e32\u0e19 \u0e1a\u0e2d\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e19\u0e32\u0e21\u0e2a\u0e01\u0e38\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e01\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e08\u0e30\u0e41\u0e27\u0e30\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e44\u0e1b\u0e1a\u0e39\u0e0a\u0e32\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e47\u0e14\u0e35<\/p>\n<p>\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07:\u00a0 25 \u0e2b\u0e21\u0e39\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22 1 \u0e41\u0e02\u0e27\u0e07\u0e04\u0e31\u0e19\u0e19\u0e32\u0e22\u0e32\u0e27 \u0e40\u0e02\u0e15\u0e04\u0e31\u0e19\u0e19\u0e32\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e<\/p>\n<p>\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: <a href=\"https:\/\/goo.gl\/maps\/UhmoMfUrDhCjWnNc8\" target=\"_blank\" rel=\"noopener\">https:\/\/goo.gl\/maps\/UhmoMfUrDhCjWnNc8<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-34893\" src=\"https:\/\/cdn.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-844x550.jpg\" alt=\"\" width=\"844\" height=\"550\" srcset=\"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-844x550.jpg 844w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-614x400.jpg 614w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-307x200.jpg 307w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-1536x1001.jpg 1536w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-2048x1335.jpg 2048w, https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-content\/uploads\/2022\/05\/aw_insert-05-1-8-770x502.jpg 770w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<p><strong>\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e17\u0e18\u0e32\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/strong><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e22\u0e21\u0e39\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e01\u0e25 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e41\u0e04\u0e48\u0e21\u0e32\u0e17\u0e35\u0e48\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e17\u0e18\u0e32\u0e23\u0e32\u0e21\u0e0b\u0e2d\u0e22\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19 19 \u0e01\u0e47\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e02\u0e2d\u0e1e\u0e23\u0e08\u0e32\u0e01\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e41\u0e25\u0e49\u0e27 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e16\u0e36\u0e07 2 \u0e2d\u0e07\u0e04\u0e37\u0e04\u0e37\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e25\u0e47\u0e01\u0e40\u0e17\u0e17\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e35 2530 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32 8 \u0e40\u0e21\u0e15\u0e23\u0e15\u0e31\u0e49\u0e07\u0e15\u0e23\u0e30\u0e2b\u0e07\u0e48\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e25\u0e07\u0e32\u0e41\u0e08\u0e49\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u0e41\u0e15\u0e48\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e34\u0e28\u0e01\u0e47\u0e2b\u0e25\u0e31\u0e48\u0e07\u0e44\u0e2b\u0e25\u0e21\u0e32\u0e17\u0e33\u0e1a\u0e38\u0e0d\u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e1a\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e02\u0e32\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e0a\u0e49\u0e32\u0e08\u0e19\u0e14\u0e36\u0e01\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19<br \/>\n\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: \u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 403 \u0e0b\u0e2d\u0e22\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 46 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e41\u0e02\u0e27\u0e07\u0e1a\u0e32\u0e07\u0e25\u0e33\u0e20\u0e39\u0e25\u0e48\u0e32\u0e07 \u0e40\u0e02\u0e15\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e<br \/>\n\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: <a href=\"https:\/\/goo.gl\/maps\/W9iq13WngbDAaxsJA\" target=\"_blank\" rel=\"noopener\">https:\/\/goo.gl\/maps\/W9iq13WngbDAaxsJA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e22\u0e21\u0e39\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e23\u0e30\u0e41\u0e2a\u0e17\u0e35\u0e48\u0e41\u0e23\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e35 2565 \u0e19\u0e35\u0e49\u0e04\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e49\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e44\u0e2b\u0e27\u0e49\u0e02\u0e2d\u0e1e\u0e23 \u201c\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e49\u0e32\u0e27\u0e08\u0e15\u0e38\u0e42\u0e25\u0e01\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e34\u0e28\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e01\u0e1b\u0e31\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e34\u0e28\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e08\u0e15\u0e38\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e34\u0e01\u0e32 \u0e40\u0e17\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e19\u0e35\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e19\u0e21\u0e37\u0e2d\u0e22\u0e31\u0e07\u0e16\u0e37\u0e2d\u0e15\u0e30\u0e1a\u0e2d\u0e07 \u0e21\u0e35\u0e17\u0e48\u0e32\u0e17\u0e32\u0e07\u0e19\u0e48\u0e32\u0e40\u0e01\u0e23\u0e07\u0e02\u0e32\u0e21 \u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e0a\u0e31\u0e48\u0e27\u0e23\u0e49\u0e32\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e17\u0e1e\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e21\u0e35\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e21\u0e32\u0e01 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e44\u0e1b\u0e02\u0e2d\u0e1e\u0e23\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e25\u0e30\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e1b\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e17\u0e48\u0e32\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e30\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35 5 \u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e19\u0e34\u0e22\u0e21\u0e44\u0e1b\u0e44\u0e2b\u0e27\u0e49\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e31\u0e19 \u0e27\u0e31\u0e14\u0e08\u0e38\u0e2c\u0e32\u0e21\u0e13\u0e35 \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e08\u0e38\u0e14\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e2d\u0e1a\u0e19\u0e35\u0e49\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e27\u0e31\u0e14\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e14\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48\u0e41\u0e16\u0e27\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e17\u0e2d\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e23\u0e38\u0e14\u0e42\u0e17\u0e23\u0e21\u0e15\u0e32\u0e21\u0e01\u0e32\u0e25\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e30\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35 2459 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e21\u0e32\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e23\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e08\u0e38\u0e14\u0e40\u0e14\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2d\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e44\u0e14\u0e49\u0e21\u0e32\u0e02\u0e2d\u0e1e\u0e23\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e17\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: 93 \u0e2b\u0e21\u0e39\u0e48 9 \u0e15\u0e33\u0e1a\u0e25\u0e1a\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48: https:\/\/goo.gl\/maps\/rxGYvStCHWwC4uXj8 \u0e27\u0e31\u0e14\u0e2a\u0e38\u0e17\u0e31\u0e28\u0e19\u0e40\u0e17\u0e1e\u0e27\u0e23\u0e32\u0e23\u0e32\u0e21\u0e23\u0e32\u0e0a\u0e27\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e27\u0e31\u0e14\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e27\u0e31\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e23\u0e32\u0e21\u0e2b\u0e25\u0e27\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e2d\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e0a\u0e34\u0e07\u0e0a\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e27\u0e31\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e28\u0e23\u0e35\u0e28\u0e32\u0e01\u0e22\u0e21\u0e38\u0e13\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e48\u0e2d\u0e42\u0e15\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e39\u0e1b\u0e2b\u0e25\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e33\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 600 \u0e1b\u0e35 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e27\u0e31\u0e14\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16 2 \u0e2b\u0e25\u0e31\u0e07\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1b\u0e49\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16\u0e17\u0e35\u0e48\u0e22\u0e32\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e35\u0e08\u0e34\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1d\u0e32\u0e2b\u0e19\u0e31\u0e07\u0e17\u0e35\u0e48\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e07\u0e14\u0e07\u0e32\u0e21\u0e21\u0e32\u0e01\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e30\u0e21\u0e35\u0e17\u0e49\u0e32\u0e27\u0e40\u0e27\u0e2a\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e21\u0e32\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07: 146 \u0e16\u0e19\u0e19\u0e15\u0e35\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":34888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[600,15,11],"tags":[],"class_list":["post-34887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-review","category-live-with-passion","category-travelholic"],"_links":{"self":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/34887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/comments?post=34887"}],"version-history":[{"count":0,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/posts\/34887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media\/34888"}],"wp:attachment":[{"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/media?parent=34887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/categories?post=34887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ananda.co.th\/blog\/thegenc\/wp-json\/wp\/v2\/tags?post=34887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}